
{"id":1264,"date":"2017-11-02T07:30:15","date_gmt":"2017-11-02T09:30:15","guid":{"rendered":"http:\/\/blog.guairaimoveis.com.br\/?p=1264"},"modified":"2024-01-31T14:27:39","modified_gmt":"2024-01-31T17:27:39","slug":"problemas-com-chuvas-telhados-e-calhas","status":"publish","type":"post","link":"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/","title":{"rendered":"Problemas com chuvas, telhados e calhas"},"content":{"rendered":"<h2>Entenda a raiz dos conflitos, as responsabilidades e por que realizar a limpeza faz toda a diferen\u00e7a.<\/h2>\n<p>Novembro chegou e com ele as chuvas do m\u00eas tamb\u00e9m. Costumeiramente, o m\u00eas inicia o per\u00edodo de chuvas pr\u00f3ximo ao ver\u00e3o e traz, al\u00e9m de mudan\u00e7as na temperatura das cidades, maior n\u00edvel pluvial e uma s\u00e9rie de problemas e discuss\u00f5es entre inquilinos e propriet\u00e1rios por conta da famosa limpeza das calhas do im\u00f3vel.<\/p>\n<p>Esse processo &#8211; que serve basicamente para os locat\u00e1rios de im\u00f3veis que n\u00e3o sejam em pr\u00e9dios &#8211; \u00e9 cheio de detalhes importantes que vamos abordar no artigo de hoje. Na hora do conserto, por exemplo, quem deve arcar com os custos? O inquilino ou o propriet\u00e1rio?<\/p>\n<p>Conforme j\u00e1 falamos em <a href=\"https:\/\/guairaimoveis.com.br\/blog\/direitos-e-deveres-do-locador-e-locatario\/\" target=\"_blank\" rel=\"noopener\">outro post<\/a>, sabemos que uma das obriga\u00e7\u00f5es do inquilino \u00e9 a de manter o im\u00f3vel nas mesmas condi\u00e7\u00f5es em que o recebeu, realizando o conserto de tudo que estragou durante o per\u00edodo em que residiu no im\u00f3vel. Tamb\u00e9m sabemos que o locador deve arcar com os custos de tudo que for necess\u00e1rio para manter o im\u00f3vel em condi\u00e7\u00f5es de ser usado pelo inquilino.<\/p>\n<p>Como definido no Artigo 23 da Lei do Inquilino, o locat\u00e1rio tamb\u00e9m tem por obriga\u00e7\u00e3o fazer a manuten\u00e7\u00e3o e conserva\u00e7\u00e3o das instala\u00e7\u00f5es e equipamentos hidr\u00e1ulicos, el\u00e9tricos, mec\u00e2nicos e de seguran\u00e7a, de uso comum. Essa obriga\u00e7\u00e3o representa um ponto importante, pois \u00e9 desse tipo de manuten\u00e7\u00e3o e de uma m\u00e1 conserva\u00e7\u00e3o dos equipamentos e espa\u00e7os da casa que surgem os problemas quando as chuvas come\u00e7am.<\/p>\n<p>Vamos imaginar o seguinte caso: o inquilino contratou um t\u00e9cnico para fazer a instala\u00e7\u00e3o de uma antena no telhado do im\u00f3vel. O t\u00e9cnico fez a instala\u00e7\u00e3o no teto e tudo correu perfeitamente, at\u00e9 as chuvas chegarem e come\u00e7arem a danificar a parte interna do im\u00f3vel, criando problemas de infiltra\u00e7\u00e3o e mofo no teto. Por conta disso, o inquilino percebe que o telhado est\u00e1 com algumas telhas quebradas que est\u00e3o ocasionando esse problema. Isso lhe parece familiar, n\u00e3o \u00e9 mesmo?<\/p>\n<p>Se nessa hist\u00f3ria voc\u00ea \u00e9 o inquilino, prepare-se: como uma pessoa subiu no telhado, esque\u00e7a seu direito. N\u00e3o h\u00e1 como provar que essa telha j\u00e1 estava quebrada antes do t\u00e9cnico subir no telhado, pisar e quebrar a telha. Logo, \u00e9 voc\u00ea quem arcar\u00e1 com essa despesa.<\/p>\n<p>Esse \u00e9 apenas um dos exemplos de situa\u00e7\u00f5es que podem ocorrer e que, para muitos, n\u00e3o eximia o locador de sua responsabilidade. Mas exime. Outro caso como esse \u00e9 quando existem obras para a manuten\u00e7\u00e3o do im\u00f3vel. Elas tamb\u00e9m s\u00e3o de responsabilidade do locat\u00e1rio que est\u00e1 utilizando o im\u00f3vel. No entanto, quando as obras s\u00e3o estruturais, quem deve arcar com o custo \u00e9 o locador. Problemas como calha entupida logo na primeira chuva depois que o inquilino fez sua mudan\u00e7a s\u00e3o de responsabilidade do propriet\u00e1rio. O locat\u00e1rio, neste caso, deve acionar a imobili\u00e1ria que tem um prazo de mais ou menos 12 horas para acionar o propriet\u00e1rio para que este, por sua vez, realize a limpeza da calha.<\/p>\n<p>Importante ressaltar: caso seja um simples entupimento de calha que exija apenas a limpeza da mesma, se o inquilino j\u00e1 estiver no im\u00f3vel a bastante tempo, deve arcar com a despesa. Mas se houver a necessidade de troca de pe\u00e7as da estrutura hidr\u00e1ulica da casa, a responsabilidade passa a ser do dono do im\u00f3vel.<\/p>\n<h3>Locador ou locat\u00e1rio? Veja quem s\u00e3o os respons\u00e1veis em cada um dos casos abaixo:<\/h3>\n<p>Pragas urbanas como morcegos, cupins, baratas e ratos n\u00e3o s\u00e3o responsabilidade de nenhum dos dois, locador ou locat\u00e1rio, devendo quem habita o im\u00f3vel tentar conter o avan\u00e7o da praga com produtos adequados, uma boa higiene do im\u00f3vel e solicitar ajuda da vigil\u00e2ncia epidemiol\u00f3gica da cidade.<\/p>\n<p><strong>\u00bb LOCADOR<\/strong><\/p>\n<p>\u00c9 respons\u00e1vel pelo pagamento de todos os consertos que forem fundamentais para manter o im\u00f3vel em condi\u00e7\u00f5es de ser utilizado, tais como:<\/p>\n<p>\u2022 troca de telhas quebradas;<br \/>\n\u2022 troca de calhas furadas ou quebradas;<br \/>\n\u2022 troca de caixa d\u2019\u00e1gua e equipamentos;<br \/>\n\u2022 troca de caixa de esgoto;<br \/>\n\u2022 troca de tubula\u00e7\u00f5es de \u00e1gua internas (dentro das paredes);<br \/>\n\u2022 troca de registros de \u00e1gua quando necess\u00e1rio quebrar a parede;<br \/>\n\u2022 troca de caixa de luz e\/ou poste de sustenta\u00e7\u00e3o do rel\u00f3gio;<br \/>\n\u2022 troca de port\u00e3o externo;<br \/>\n\u2022 conserto de muro externo em caso de a\u00e7\u00e3o do tempo;<br \/>\n\u2022 conserto de telhado em caso de a\u00e7\u00e3o do tempo;<br \/>\n\u2022 conserto de tudo no im\u00f3vel, que estiver com problema no uso, anterior \u00e0 loca\u00e7\u00e3o;<br \/>\n\u2022 conserto de tubula\u00e7\u00e3o externa e interna de esgoto;<br \/>\n\u2022 pintura externa do im\u00f3vel;<br \/>\n\u2022 cal\u00e7amento externo do im\u00f3vel;<br \/>\n\u2022 troca do poste de sustenta\u00e7\u00e3o do rel\u00f3gio de luz (casas);<br \/>\n\u2022 troca da caixa e instala\u00e7\u00e3o do rel\u00f3gio (quando exigido pela empresa de energia).<\/p>\n<p>Importante lembrar: o inquilino deve avisar imediatamente o locador por escrito de qualquer problema no im\u00f3vel sob pena de ser responsabilizado pelos danos caso sejam ampliados pela falta da comunica\u00e7\u00e3o.<\/p>\n<p><strong>\u00bb LOCAT\u00c1RIO<\/strong><\/p>\n<p>Como afirmamos acima, o inquilino fica respons\u00e1vel pela manuten\u00e7\u00e3o do im\u00f3vel enquanto nele residir, devendo consertar tudo o que estragar. Tem o dever de, ao entrar no im\u00f3vel, fazer a vistoria juntamente com o vistoriador da imobili\u00e1ria e solicitar ao locador, por escrito, que conserte tudo que estiver com problemas. Caso n\u00e3o comunique esses consertos necess\u00e1rios, fica subentendido que o inquilino aceitou o im\u00f3vel na forma que lhe foi entregue e, depois disso, n\u00e3o poder\u00e1 pedir nenhuma altera\u00e7\u00e3o para o propriet\u00e1rio.<\/p>\n<p>Outro caso que costuma gerar d\u00favidas: \u00e9 muito comum que o inquilino, ao entrar no im\u00f3vel, encontre uma torneira pingando. Como n\u00e3o o incomoda no momento, deixa da mesma forma at\u00e9 que ela quebre completamente. Mais para frente, quando descobre que ter\u00e1 que trocar a torneira, pede para que o locador arque com os custos, pois quando come\u00e7ou a morar no im\u00f3vel o problema j\u00e1 existia. Neste caso, entende-se que quem provocou o dano foi o pr\u00f3prio inquilino, j\u00e1 que n\u00e3o pediu ao locador o reparo. Por conta disso, o problema se agravou at\u00e9 que a \u00fanica solu\u00e7\u00e3o implicasse na troca da torneira.<\/p>\n<p>O inquilino deve consertar e arcar com os custos nos seguintes casos:<\/p>\n<p>\u2022 conserto ou troca de torneiras de prefer\u00eancia da mesma marca e tipo. No caso de n\u00e3o haver mais a mesma torneira \u00e0 venda, deve-se colocar uma de mesmo padr\u00e3o;<br \/>\n\u2022 conserto ou troca de todo o encanamento externo do im\u00f3vel como cano das lou\u00e7as sanit\u00e1rias e pias da cozinha e tanque;<br \/>\n\u2022 troca de disjuntores estragados e manuten\u00e7\u00e3o do rel\u00f3gio de luz e sua fia\u00e7\u00e3o;<br \/>\n\u2022 troca de tomadas de energia el\u00e9trica por outras de mesmo padr\u00e3o quando estragadas;<br \/>\n\u2022 troca ou conserto da v\u00e1lvula hidra do vaso sanit\u00e1rio bem como as borrachas de veda\u00e7\u00e3o, registro de \u00e1gua com instala\u00e7\u00e3o externa (que n\u00e3o precise quebrar paredes) e assentos quebrados;<br \/>\n\u2022 troca de vidros quebrados ou lascados;<br \/>\n\u2022 troca ou conserto de fechaduras externas ou internas no mesmo padr\u00e3o;<br \/>\n\u2022 conserto das fechaduras internas e chaves;<br \/>\n\u2022 troca de cer\u00e2micas ou azulejos que forem lascados ou quebrados;<br \/>\n\u2022 conserto ou troca do interfone do im\u00f3vel e campainha;<br \/>\n\u2022 conserto da fia\u00e7\u00e3o el\u00e9trica quando o problema for causado pelo pr\u00f3prio inquilino (uso inadequado de equipamentos com pot\u00eancia superior \u00e0 rede el\u00e9trica do im\u00f3vel);<br \/>\n\u2022 limpeza e desentupimento de vasos sanit\u00e1rios, pias, caixa de gordura e esgoto, ralos e canos e fossa externa (casas);<br \/>\n\u2022 manuten\u00e7\u00e3o da \u00e1rea externa do im\u00f3vel (casas) como piso, muros e port\u00f5es, mantendo-os em perfeito funcionamento;<br \/>\n\u2022 limpeza de telhado e calha externa mantendo-os desobstru\u00eddos de folhas e sujeira que provoquem entupimento e poss\u00edvel infiltra\u00e7\u00e3o no im\u00f3vel;<br \/>\n\u2022 limpeza das paredes mais suscet\u00edveis ao mofo por excesso de umidade (im\u00f3vel voltado para o sul com pouca ou nenhuma incid\u00eancia de sol), que fique fechado na maior parte do dia ou situado abaixo do n\u00edvel da rua.<\/p>\n<h3>\u00c9poca de chuvas<\/h3>\n<p>\u00c9 muito importante ficar atento \u00e0 limpeza das calhas! Verifique se o telhado est\u00e1 com alguma telha quebrada e se o im\u00f3vel precisa de qualquer tipo de conserto. Limpar uma calha \u00e9 mais barato que o estrago que ela pode fazer caso esteja suja. O mesmo vale para a troca de uma telha quebrada ou compra de uma nova para tapar um buraco.<\/p>\n<p>Fique atento tamb\u00e9m ao esquema de seguro para locat\u00e1rio. Os consertos funcionam de forma diferente, pois quem \u00e9 segurado tem direito a um rol de coberturas de consertos e manuten\u00e7\u00f5es.<\/p>\n<h3>Como funciona na Gua\u00edra?<\/h3>\n<p>Caso o locat\u00e1rio necessite, dever\u00e1 entrar em contato com a imobili\u00e1ria para solicitar o reparo. O processo ocorrer\u00e1 da seguinte forma:<\/p>\n<p><strong>a.<\/strong> Envio da solicita\u00e7\u00e3o pelo e-mail manutencao@guairaimoveis.com.br, juntamente com um or\u00e7amento de um prestador de servi\u00e7os de sua confian\u00e7a (sem o qual n\u00e3o haver\u00e1 contato com o Locador). Se poss\u00edvel, dever\u00e1 enviar fotos do reparo a ser efetuado pois isso agiliza o processo;<\/p>\n<p><strong>b.<\/strong> O prazo de resposta da imobili\u00e1ria \u00e9 de, no m\u00e1ximo, 12 horas;<\/p>\n<p><strong>c.<\/strong> Caso o reparo seja autorizado, o locat\u00e1rio dever\u00e1 apresentar a Nota Fiscal do valor combinado para que seja aplicado o desconto em aluguel posterior (conforme acordado entre as partes);<\/p>\n<p><strong>d.<\/strong> Al\u00e9m de apresentar a NF (ou recibo), o locat\u00e1rio dever\u00e1 enviar as fotos do reparo realizado ou agendar uma visita do Vistoriador da imobili\u00e1ria para verifica\u00e7\u00e3o do reparo efetuado.<\/p>\n<p>Sempre que necess\u00e1rio, o inquilino poder\u00e1 entrar em contato com a imobili\u00e1ria para esclarecer maiores d\u00favidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entenda a raiz dos conflitos, as responsabilidades e por que realizar a limpeza faz toda a diferen\u00e7a.<\/p>\n","protected":false},"author":2,"featured_media":1263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[93,125,225,75,474],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Problemas com chuvas, telhados e calhas - Blog da Gua\u00edra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Problemas com chuvas, telhados e calhas - Blog da Gua\u00edra\" \/>\n<meta property=\"og:description\" content=\"Entenda a raiz dos conflitos, as responsabilidades e por que realizar a limpeza faz toda a diferen\u00e7a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Gua\u00edra\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-02T09:30:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T17:27:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2017\/11\/171102-chuvas-calhas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Problemas com chuvas, telhados e calhas - Blog da Gua\u00edra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/","og_locale":"pt_BR","og_type":"article","og_title":"Problemas com chuvas, telhados e calhas - Blog da Gua\u00edra","og_description":"Entenda a raiz dos conflitos, as responsabilidades e por que realizar a limpeza faz toda a diferen\u00e7a.","og_url":"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/","og_site_name":"Blog da Gua\u00edra","article_published_time":"2017-11-02T09:30:15+00:00","article_modified_time":"2024-01-31T17:27:39+00:00","og_image":[{"width":1920,"height":600,"url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2017\/11\/171102-chuvas-calhas.png","type":"image\/png"}],"author":"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/#article","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/"},"author":{"name":"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/40e0b9c04f378050e2a50c39a880ca48"},"headline":"Problemas com chuvas, telhados e calhas","datePublished":"2017-11-02T09:30:15+00:00","dateModified":"2024-01-31T17:27:39+00:00","mainEntityOfPage":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/"},"wordCount":1675,"commentCount":2,"publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"keywords":["calha entupida","como cuidar da casa em \u00e9poca de chuva","direitos e deveres do locador e locat\u00e1rio","\u00e9poca de chuvas","telha quebrada"],"articleSection":["Loca\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/","url":"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/","name":"Problemas com chuvas, telhados e calhas - Blog da Gua\u00edra","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#website"},"datePublished":"2017-11-02T09:30:15+00:00","dateModified":"2024-01-31T17:27:39+00:00","breadcrumb":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/guairaimoveis.com.br\/blog\/problemas-com-chuvas-telhados-e-calhas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/guairaimoveis.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Problemas com chuvas, telhados e calhas"}]},{"@type":"WebSite","@id":"https:\/\/guairaimoveis.com.br\/blog\/#website","url":"https:\/\/guairaimoveis.com.br\/blog\/","name":"Blog da Gua\u00edra","description":"Aqui voc\u00ea vai encontrar conte\u00fados incr\u00edveis sobre o mercado imobili\u00e1rio e tirar todas as d\u00favidas que voc\u00ea tem na hora de comprar, alugar ou negociar um im\u00f3vel.","publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"alternateName":"Gua\u00edra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guairaimoveis.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization","name":"Blog da Gua\u00edra","url":"https:\/\/guairaimoveis.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","contentUrl":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","width":200,"height":55,"caption":"Blog da Gua\u00edra"},"image":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/40e0b9c04f378050e2a50c39a880ca48","name":"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4f6f5c8fa05083d65db1b175f0c4b8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f6f5c8fa05083d65db1b175f0c4b8b0?s=96&d=mm&r=g","caption":"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios"},"sameAs":["growww"],"url":"https:\/\/guairaimoveis.com.br\/blog\/author\/blogguairaimoveis\/"}]}},"_links":{"self":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/1264"}],"collection":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1264"}],"version-history":[{"count":1,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/1264\/revisions"}],"predecessor-version":[{"id":5751,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/1264\/revisions\/5751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media\/1263"}],"wp:attachment":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}