
{"id":1501,"date":"2018-03-08T08:00:36","date_gmt":"2018-03-08T11:00:36","guid":{"rendered":"http:\/\/blog.guairaimoveis.com.br\/?p=1501"},"modified":"2018-03-08T08:00:36","modified_gmt":"2018-03-08T11:00:36","slug":"a-mulher-e-o-mercado-imobiliario","status":"publish","type":"post","link":"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/","title":{"rendered":"A mulher e o Mercado Imobili\u00e1rio"},"content":{"rendered":"<h2><span style=\"font-weight:400;\">O mercado imobili\u00e1rio mudou e passou a ter a presen\u00e7a forte das mulheres. Entenda o porqu\u00ea.<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight:400;\">Estamos em 2018. \u00c9 ineg\u00e1vel que as mulheres conquistaram muitos espa\u00e7os de trabalho que antes n\u00e3o eram abertos para elas. E o <strong>mercado imobili\u00e1rio<\/strong> com certeza \u00e9 um deles. Apesar da presen\u00e7a ainda muito forte dos homens como <strong>corretores imobili\u00e1rios<\/strong>, diretores de imobili\u00e1rias e respons\u00e1veis pela constru\u00e7\u00e3o civil, as mulheres hoje j\u00e1 adentraram consideravelmente nestes ambientes.<\/span><\/p>\n<p><span style=\"font-weight:400;\">Para se ter ideia, de acordo com o Minist\u00e9rio do Trabalho e Emprego, entre 2007 e 2009, a constru\u00e7\u00e3o civil viu um aumento de 44,5% na <strong>contrata\u00e7\u00e3o de mulheres<\/strong>. Hoje, a estimativa \u00e9 de que mais de 200 mil mulheres trabalhem na \u00e1rea, de maneira formal ou aut\u00f4noma. No caso das <strong>corretoras<\/strong>, o n\u00famero \u00e9 ainda mais animador: <strong>no Brasil, a participa\u00e7\u00e3o das mulheres corretoras representa 48% dos profissionais da \u00e1rea em atua\u00e7\u00e3o. Em 1995, as mulheres representavam apenas 8,3% dos corretores de im\u00f3veis do pa\u00eds.<\/strong><\/span><\/p>\n<p><span style=\"font-weight:400;\">\u00c9 interessante observar como elas ganharam espa\u00e7o e se tornaram bem-sucedidas profissionais nos diferentes setores do <strong>mercado imobili\u00e1rio<\/strong> em um relativamente curto espa\u00e7o de tempo, mostrando \u00f3timo desempenho e ganhando destaque entre corretores. Pode-se dizer que o segredo \u00e9 muita disciplina, empenho e dedica\u00e7\u00e3o individuais, caracter\u00edsticas muito comuns e culturalmente desenvolvidas pelas mulheres e que ajudam consideravelmente nesse processo.<\/span><\/p>\n<p><span style=\"font-weight:400;\">Dentro de todas essas mudan\u00e7as e evolu\u00e7\u00e3o do cen\u00e1rio imobili\u00e1rio, \u00e9 importante enxergarmos como essa revolu\u00e7\u00e3o come\u00e7ou l\u00e1 atr\u00e1s, no meio do s\u00e9culo XX. <\/span><\/p>\n<p>&nbsp;<\/p>\n<h2>A participa\u00e7\u00e3o da mulher no mercado imobili\u00e1rio<\/h2>\n<p><span style=\"font-weight:400;\">Basicamente falando, as mulheres eram proibidas de trabalhar como <strong>corretoras de im\u00f3veis<\/strong> at\u00e9 1958, pois at\u00e9 este ano, existia um artigo no C\u00f3digo Comercial Brasileiro &#8211; o artigo 37 &#8211; que proibia as mulheres de atuar como <strong>corretoras de im\u00f3veis<\/strong>. A partir deste ano, houve uma abertura do mercado a qual possibilitou que elas trabalhassem na \u00e1rea e mostrassem todas as caracter\u00edsticas que proporcionaram o reconhecimento que hoje elas possuem. <\/span><\/p>\n<p><span style=\"font-weight:400;\">Tecnicamente falando, faz apenas 60 anos que as mulheres t\u00eam permiss\u00e3o oficial para trabalhar na \u00e1rea e neste pouco tempo elas conquistaram um sucesso bastante grande. E essa afirmativa \u00e9 apoiada pelo COFECI (Conselho Federal de Corretores de Im\u00f3veis), por exemplo, que apontou um crescimento de 144% na participa\u00e7\u00e3o feminina na \u00faltima d\u00e9cada, segundo uma pesquisa deles. <\/span><\/p>\n<p><span style=\"font-weight:400;\">Uma das pioneiras na \u00e1rea foi a <strong>corretora de im\u00f3veis Marly da Silveira Ferreira<\/strong>, que come\u00e7ou a trabalhar nessa \u00e1rea em 1976, e se tornou a primeira mulher a assumir a presid\u00eancia do tamb\u00e9m pioneiro Sindicato dos Corretores de Im\u00f3veis do Munic\u00edpio do Rio de Janeiro. Esse sindicato, fundado h\u00e1 78 anos, surgiu antes da regulamenta\u00e7\u00e3o da profiss\u00e3o de corretor de im\u00f3veis e teve presen\u00e7a fundamental na cria\u00e7\u00e3o de outras entidades, como os Creci\u2019s, o Cofeci e a Fenaci.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2>A competitividade no mercado<\/h2>\n<p><span style=\"font-weight:400;\">\u00c9 importante deixar claro que \u00a0trabalhar como corretora n\u00e3o \u00e9 algo f\u00e1cil e simples. Trata-se de um mercado dif\u00edcil e bastante competitivo, j\u00e1 que a concorr\u00eancia \u00e9 grande e muitas vezes desleal. No entanto, as corretoras costumam vender mais, pois s\u00e3o mais sens\u00edveis na hora de fazer o atendimento e prestam mais aten\u00e7\u00e3o aos detalhes emocionais. A mulher tem mais facilidade de enxergar a vida do outro, se coloca mais facilmente no lugar da outra pessoa e isso facilita a negocia\u00e7\u00e3o e fechamento da venda. <\/span><\/p>\n<p><span style=\"font-weight:400;\">A competitividade existe tamb\u00e9m dentro do pr\u00f3prio mercado. Apesar de ser negativo, muitos homens se sentem amea\u00e7ados quando encontram mulheres muito competentes trabalhando como <strong>corretoras<\/strong>. O que acontece, muitas vezes, \u00e9 um boicote com essa profissional. \u00c9 \u00f3bvio que estas s\u00e3o as exce\u00e7\u00f5es, mas isso pode ser um entrave em alguns casos, pois a profissional come\u00e7a a perder oportunidades de vagas em plant\u00f5es ou acessos a clientes que poderiam comprar com ela. <\/span><\/p>\n<p><span style=\"font-weight:400;\">Com esse tipo de situa\u00e7\u00e3o acontecendo, as mulheres j\u00e1 est\u00e3o bem mais ligadas e t\u00eam estudado muito para se aprimorar e vender cada vez mais. Esse definitivamente \u00e9 um ponto importante da performance de homens e mulheres, mas elas est\u00e3o correndo mais atr\u00e1s de conhecimento. Isso naturalmente melhora o desempenho delas e proporciona uma carreira de mais sucesso. <\/span><\/p>\n<p><span style=\"font-weight:400;\">Existem alguns caminhos para se tornar uma corretora ou corretor de im\u00f3veis, obtendo o registro oficial. S\u00e3o eles: <\/span><\/p>\n<p><span style=\"font-weight:400;\">&gt;&gt; TTI (T\u00e9cnico de Transa\u00e7\u00f5es Imobili\u00e1rias);<\/span><\/p>\n<p><span style=\"font-weight:400;\">&gt;&gt; Curso Superior de Tecnologia em Neg\u00f3cios Imobili\u00e1rios;<\/span><\/p>\n<p><span style=\"font-weight:400;\">&gt;&gt; Curso Superior de Gest\u00e3o em Neg\u00f3cios Imobili\u00e1rios;<\/span><\/p>\n<p><span style=\"font-weight:400;\">&gt;&gt; P\u00f3s-gradua\u00e7\u00e3o em Neg\u00f3cios Imobili\u00e1rios.<\/span><\/p>\n<p><span style=\"font-weight:400;\">E \u00e9 preciso ficar ligado e sempre buscar atualiza\u00e7\u00e3o profissional, j\u00e1 que o mercado \u00e9 bastante din\u00e2mico. <\/span><\/p>\n<p>&nbsp;<\/p>\n<h2>Diferenciais do atendimento da mulher corretora<\/h2>\n<p><span style=\"font-weight:400;\">Como j\u00e1 apontamos acima, as mulheres possuem uma aten\u00e7\u00e3o especial aos detalhes e ao lado emocional da negocia\u00e7\u00e3o. Isso ajuda muito na hora de fechar neg\u00f3cios. Mas existem outros diferenciais tamb\u00e9m como, por exemplo, a imagina\u00e7\u00e3o e criatividade para solucionar o problema na hora de uma venda ou de alugar um im\u00f3vel para um cliente. Elas costumam ter maior facilidade na hora de indicar uma reforma ou um novo uso para um c\u00f4modo que o cliente n\u00e3o gostou tanto e d\u00e3o \u00f3timas dicas de decora\u00e7\u00e3o, muitas vezes melhores do que as dos homens. <\/span><\/p>\n<p><span style=\"font-weight:400;\">Outro ponto importante \u00e9 que elas conhecidas por serem muito comunicativas e isso est\u00e1 sendo visto como um ponto extremamente positivo. Devido \u00e0 postura aberta, proativa e sincera com que as mulheres trabalham as rela\u00e7\u00f5es com os clientes, a comunica\u00e7\u00e3o fica mais clara e consequentemente o atendimento ganha mais qualidade. Al\u00e9m disso, essa facilidade na comunica\u00e7\u00e3o ajuda a construir o networking na \u00e1rea. <\/span><\/p>\n<p><span style=\"font-weight:400;\">Por \u00faltimo, \u00e9 interessante notar que mesmo com toda a evolu\u00e7\u00e3o das \u00faltimas d\u00e9cadas, a inser\u00e7\u00e3o maior da <strong>mulher no mercado imobili\u00e1rio<\/strong> e com a aceita\u00e7\u00e3o dos clientes, ainda existem muitos desafios e diversas barreiras a serem rompidas pelas mulheres no mercado de trabalho, em especial no imobili\u00e1rio.\u00a0<\/span>Por\u00e9m, guerreiras que s\u00e3o, com jornadas duplas e \u00e0s vezes triplas (trabalho, casa, maternidade), essas leoas est\u00e3o mostrando que vieram para ficar.<\/p>\n<h2><strong>Esse artigo \u00e9 uma homenagem \u00e0 voc\u00eas, mulheres do mercado imobili\u00e1rio, pelo seu dia. Feliz dia Internacional da Mulher.<\/strong><\/h2>\n<div id=\"attachment_1503\" style=\"width: 1930px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1503\" class=\"wp-image-1503 size-full\" title=\"For\u00e7a da Mulher no Mercado Imobiliario\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2018\/03\/leoa.png\" alt=\"\" width=\"1920\" height=\"700\" srcset=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/03\/leoa.png 1920w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/03\/leoa-300x109.png 300w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/03\/leoa-1024x373.png 1024w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/03\/leoa-768x280.png 768w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/03\/leoa-1536x560.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><p id=\"caption-attachment-1503\" class=\"wp-caption-text\">Representa\u00e7\u00e3o da For\u00e7a da Mulher no Mercado Imobiliario<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight:400;\">Fontes:<\/span><\/p>\n<p><a href=\"https:\/\/constructapp.io\/pt\/precisamos-falar-sobre-a-presenca-da-mulher-na-construcao-civil\/\"><span style=\"font-weight:400;\">https:\/\/constructapp.io\/pt\/precisamos-falar-sobre-a-presenca-da-mulher-na-construcao-civil\/<\/span><\/a><\/p>\n<p><a href=\"https:\/\/estadodeminas.lugarcerto.com.br\/app\/noticia\/noticias\/2016\/10\/16\/interna_noticias,49596\/mulheres-representam-30-dos-25-mil-corretores-de-imoveis-atuantes-em.shtml\"><span style=\"font-weight:400;\">https:\/\/estadodeminas.lugarcerto.com.br\/app\/noticia\/noticias\/2016\/10\/16\/interna_noticias,49596\/mulheres-representam-30-dos-25-mil-corretores-de-imoveis-atuantes-em.shtml<\/span><\/a><\/p>\n<p><a href=\"http:\/\/www.ingaia.com.br\/mulheres-no-mercado-imobiliario-entenda-por-que-elas-vendem-mais\/\"><span style=\"font-weight:400;\">http:\/\/www.ingaia.com.br\/mulheres-no-mercado-imobiliario-entenda-por-que-elas-vendem-mais\/<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mercado imobili\u00e1rio mudou e passou a ter a presen\u00e7a forte das mulheres. Entenda o porqu\u00ea. &nbsp; Estamos em 2018. \u00c9 ineg\u00e1vel que as mulheres conquistaram muitos espa\u00e7os de trabalho que antes n\u00e3o eram abertos para elas. E o mercado imobili\u00e1rio com certeza \u00e9 um deles. Apesar da presen\u00e7a ainda muito forte dos homens como [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,8],"tags":[16,65,83,85,204,207,239,328,389,390],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A mulher e o Mercado Imobili\u00e1rio - Blog da Gua\u00edra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A mulher e o Mercado Imobili\u00e1rio - Blog da Gua\u00edra\" \/>\n<meta property=\"og:description\" content=\"O mercado imobili\u00e1rio mudou e passou a ter a presen\u00e7a forte das mulheres. Entenda o porqu\u00ea. &nbsp; Estamos em 2018. \u00c9 ineg\u00e1vel que as mulheres conquistaram muitos espa\u00e7os de trabalho que antes n\u00e3o eram abertos para elas. E o mercado imobili\u00e1rio com certeza \u00e9 um deles. Apesar da presen\u00e7a ainda muito forte dos homens como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Gua\u00edra\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-08T11:00:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/03\/capa-blog-1920x600-mulher1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A mulher e o Mercado Imobili\u00e1rio - Blog da Gua\u00edra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/","og_locale":"pt_BR","og_type":"article","og_title":"A mulher e o Mercado Imobili\u00e1rio - Blog da Gua\u00edra","og_description":"O mercado imobili\u00e1rio mudou e passou a ter a presen\u00e7a forte das mulheres. Entenda o porqu\u00ea. &nbsp; Estamos em 2018. \u00c9 ineg\u00e1vel que as mulheres conquistaram muitos espa\u00e7os de trabalho que antes n\u00e3o eram abertos para elas. E o mercado imobili\u00e1rio com certeza \u00e9 um deles. Apesar da presen\u00e7a ainda muito forte dos homens como [&hellip;]","og_url":"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/","og_site_name":"Blog da Gua\u00edra","article_published_time":"2018-03-08T11:00:36+00:00","og_image":[{"width":1920,"height":600,"url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/03\/capa-blog-1920x600-mulher1.jpg","type":"image\/jpeg"}],"author":"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/#article","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/"},"author":{"name":"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/40e0b9c04f378050e2a50c39a880ca48"},"headline":"A mulher e o Mercado Imobili\u00e1rio","datePublished":"2018-03-08T11:00:36+00:00","dateModified":"2018-03-08T11:00:36+00:00","mainEntityOfPage":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/"},"wordCount":1127,"commentCount":2,"publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"keywords":["8 de mar\u00e7o","aquecimento do mercado imobili\u00e1rio","benef\u00edcios das empresas familiares","blog da gua\u00edra","dia da mulher","dia internacional da mulher","empresa familiar","imobili\u00e1ria gua\u00edra","mulher corretora","mulher mercado imobili\u00e1rio"],"articleSection":["Mercado Imobili\u00e1rio","Neg\u00f3cios e Vendas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/","url":"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/","name":"A mulher e o Mercado Imobili\u00e1rio - Blog da Gua\u00edra","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#website"},"datePublished":"2018-03-08T11:00:36+00:00","dateModified":"2018-03-08T11:00:36+00:00","breadcrumb":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/guairaimoveis.com.br\/blog\/a-mulher-e-o-mercado-imobiliario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/guairaimoveis.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"A mulher e o Mercado Imobili\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/guairaimoveis.com.br\/blog\/#website","url":"https:\/\/guairaimoveis.com.br\/blog\/","name":"Blog da Gua\u00edra","description":"Aqui voc\u00ea vai encontrar conte\u00fados incr\u00edveis sobre o mercado imobili\u00e1rio e tirar todas as d\u00favidas que voc\u00ea tem na hora de comprar, alugar ou negociar um im\u00f3vel.","publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"alternateName":"Gua\u00edra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guairaimoveis.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization","name":"Blog da Gua\u00edra","url":"https:\/\/guairaimoveis.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","contentUrl":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","width":200,"height":55,"caption":"Blog da Gua\u00edra"},"image":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/40e0b9c04f378050e2a50c39a880ca48","name":"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4f6f5c8fa05083d65db1b175f0c4b8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f6f5c8fa05083d65db1b175f0c4b8b0?s=96&d=mm&r=g","caption":"Gua\u00edra Neg\u00f3cios Imobili\u00e1rios"},"sameAs":["growww"],"url":"https:\/\/guairaimoveis.com.br\/blog\/author\/blogguairaimoveis\/"}]}},"_links":{"self":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/1501"}],"collection":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1501"}],"version-history":[{"count":0,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/1501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media\/1507"}],"wp:attachment":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}