
{"id":1883,"date":"2018-09-11T11:19:21","date_gmt":"2018-09-11T14:19:21","guid":{"rendered":"http:\/\/blog.guairaimoveis.com.br\/?p=1883"},"modified":"2024-01-31T12:50:30","modified_gmt":"2024-01-31T15:50:30","slug":"plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira","status":"publish","type":"post","link":"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/","title":{"rendered":"Plantas para decorar a piscina: confira as dicas da Imobili\u00e1ria Gua\u00edra"},"content":{"rendered":"<p>Decorar a <strong>piscina com plantas<\/strong> \u00e9 sempre uma excelente ideia para deixar o<br \/>\nambiente mais aconchegante e belo; veja essas <strong>dicas da Imobili\u00e1ria Gua\u00edra.<\/strong><\/p>\n<p>A <strong>Imobili\u00e1ria Gua\u00edra<\/strong> v\u00ea a primavera se aproximando e j\u00e1 come\u00e7a a pensar em piscina.<br \/>\nN\u00e3o podemos sentir aquele calorzinho chegando sem imaginar um bom banho para<br \/>\nrefrescar o forte calor que nos espera.<\/p>\n<p>Mas muito mais do que aproveitar a piscina, \u00e9 importante tamb\u00e9m ter um espa\u00e7o para<br \/>\ncompartilhar. Contando com um paisagismo com plantas para decorar o belo recanto da\u00a0piscina para um encontro de familiares e amigos pode ser poss\u00edvel at\u00e9 em dias cinzas.<\/p>\n<p>Afinal, por que deixar uma temperatura baixa estragar o momento? Basta uma\u00a0comidinha quente (ou alguns doces \u2013 ou os dois), uma bebida para degustar e um\u00a0espa\u00e7o bonito para aproveitar.<\/p>\n<p>Pronto. A receita de um \u00f3timo dia est\u00e1 feito. O melhor disso \u00e9 que n\u00e3o s\u00e3o necess\u00e1rias<br \/>\nmirabolantes ideias arquitet\u00f4nicas para transformar o espa\u00e7o da piscina em algo<br \/>\nconfort\u00e1vel.<\/p>\n<p>A <strong>Imobili\u00e1ria Gua\u00edra<\/strong> preparou um mix de dicas formid\u00e1veis para quem deseja dar um<br \/>\ntchan! na piscina. Decorar com plantas sempre traz aquele ar de harmonia,<br \/>\ntranquilidade, conforto e aconchego.<\/p>\n<p>Que tal levar isso tamb\u00e9m para a sua casa e, claro, para sua piscina? Confira estas<br \/>\n\u00f3timas dicas da imobili\u00e1ria Gua\u00edra para voc\u00ea!<\/p>\n<h2>Imobili\u00e1ria Gua\u00edra ensina como decorar a piscina com belas plantas<\/h2>\n<p>Anda achando a piscina um pouco sem gra\u00e7a? Pois bem, uma piscina merece um<br \/>\npaisagismo minimalista que a destaque, at\u00e9 porque a beleza dela merece tal \u00eanfase.<\/p>\n<h3>Ideia minimalista, com alguns detalhes<\/h3>\n<p>Esse conceito \u00e9 bastante usado para quem ocupa a maior parte do p\u00e1tio com ladrilhos.\u00a0As plantas sim\u00e9tricas nos cantos s\u00e3o um pequeno detalhe que fazem uma grande\u00a0diferen\u00e7a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1885 size-medium\" title=\"piscina em casa e imobiliaria guaira\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guac3adra-1.png?w=300\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guac3adra-1.png 500w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guac3adra-1-300x300.png 300w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guac3adra-1-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Fa\u00e7a um exerc\u00edcio e imagine esta composi\u00e7\u00e3o de espa\u00e7o sem o <strong>decorar das plantas<\/strong>. Faz\u00a0uma boa diferen\u00e7a, certo?<\/p>\n<p>Esse primeiro exemplo \u00e9 aquele ideal para mostrar como <strong>decorar com plantas<\/strong> faz uma<br \/>\ngrande diferen\u00e7a no espa\u00e7o. O ambiente n\u00e3o apresenta o verde como destaque, por isso\u00a0\u00e9 importante para a composi\u00e7\u00e3o manter isso, pois n\u00e3o ficaria org\u00e2nico.<\/p>\n<p>Outro ponto fundamental \u00e9 se atentar ao espa\u00e7o dispon\u00edvel. Neste, por exemplo,\u00a0pequeno e simples, muitas plantas \u201cpoluiriam\u201d o visual.<\/p>\n<h3>Grama, sombras e palmeiras<\/h3>\n<p>Por que n\u00e3o compor at\u00e9 mesmo os objetos com folhas? Esse belo guarda-sol \u00e9 um<br \/>\nexemplo, e que pode ser feito em casa, artesanalmente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1886 size-medium\" title=\"piscina em casa e imobiliaria guaira imoveis\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-2.png?w=300\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-2.png 500w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-2-300x300.png 300w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-2-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Em um p\u00e1tio gramado, nada como palmeiras e essa organiza\u00e7\u00e3o com quebra-sol que<br \/>\nharmoniza com o ambiente. Uma sombrinha \u00e0s vezes \u00e9 tudo o que se precisa num dia<br \/>\nquente de sol forte.<\/p>\n<p>A <strong>Imobili\u00e1ria Gua\u00edra<\/strong> pode n\u00e3o ter os melhores especialistas em trabalhos artesanais,<br \/>\nmas pode sugerir que voc\u00ea componha sua piscina com essa maravilha de guarda-sol.<\/p>\n<p>Afinal, \u00e9 apaixonante ou n\u00e3o \u00e9?<\/p>\n<h3>O detalhe que apaixona<\/h3>\n<p>O que mais chama a aten\u00e7\u00e3o nesta imagem n\u00e3o s\u00e3o as \u00e1rvores ao fundo ou as folhas que\u00a0acusam adentrar na fotografia. O que chama a aten\u00e7\u00e3o \u00e9 aquela pequena planta (que\u00a0mais parece um pequeno galho) no vaso marrom.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1887 size-medium\" title=\"piscina em casa e imobiliaria guaira imoveis\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2018\/09\/piscina-e-imovel-e-imobiliaria-guaira-3.png?w=300\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-e-imovel-e-imobiliaria-guaira-3.png 500w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-e-imovel-e-imobiliaria-guaira-3-300x300.png 300w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-e-imovel-e-imobiliaria-guaira-3-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>O interessante de compor com esse tipo de planta \u00e9 dar vida por meio dos pequenos<br \/>\ngalhos. Marrom, discreto e ainda v\u00edvido.<\/p>\n<p>Agrada muito o uso, principalmente percebendo o pequeno deck do outro lado da<br \/>\npiscina (igualmente em cor marrom) contrastando \u00e0s pedras brancas. Tudo harmoniza.<\/p>\n<h3>Disposi\u00e7\u00e3o ordenada das plantinhas<\/h3>\n<p>Tudo bem, a riqueza tomou propor\u00e7\u00f5es enormes para quem tem uma piscina interna.<br \/>\nMas n\u00e3o \u00e9 esse o detalhe chique que queremos mostrar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1888 size-medium\" title=\"piscina em casa e imobiliaria guaira imoveis\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-4.png?w=300\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-4.png 500w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-4-300x300.png 300w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-4-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>O que a <strong>Imobili\u00e1ria Gua\u00edra<\/strong> recomenda, neste caso, \u00e9 a disposi\u00e7\u00e3o das plantas. Observe\u00a0como cada uma ocupa um pequeno espa\u00e7o.<\/p>\n<p>Sem destaques maiores, sem necessidade de sobressali\u00eancia. As plantas deram o<br \/>\ndestaque devido com o verde das folhas que glamourizam o ambiente como um todo.<\/p>\n<h3>As cl\u00e1ssicas palmeiras e coqueiros<\/h3>\n<p>Por fim, a Imobili\u00e1ria Gua\u00edra fecha com chave-de-ouro. N\u00e3o poderia faltar ela, a cl\u00e1ssica\u00a0palmeira ou ainda os coqueiros.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1889 size-medium\" title=\"piscina em casa e imobiliaria guaira imoveis\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-5.png?w=300\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-5.png 500w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-5-300x300.png 300w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-5-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Dando todo aquele ar e charme de praia, os coqueiros e palmeiras deixam qualquer<br \/>\nambiente perfeito. O detalhe faz parecer um pequeno Oasis nos fundos de casa.<\/p>\n<p>A paz adentra a alma, e parece que essa combina\u00e7\u00e3o remete \u00e0s melhores paisagens do\u00a0Caribe. Ok, foi exagerado? Um pouco. Mas a combina\u00e7\u00e3o sempre impressiona e<br \/>\nproporciona um ar \u00fanico, apesar de cl\u00e1ssico.<\/p>\n<h3>A Imobili\u00e1ria Gua\u00edra pronta para ajudar nos detalhes<\/h3>\n<p>Seja dicas para o seu banheiro ou at\u00e9 mesmo indicar as melhores imobili\u00e1rias de Santo\u00a0Andr\u00e9. A <strong>Imobili\u00e1ria Gua\u00edra<\/strong> \u00e9, como diz o ditado, \u201cpau para toda a obra\u201d.<\/p>\n<p>Pronta para ajudar o cliente, pronta para ser o bra\u00e7o direito de quem precisa. Pronta para\u00a0auxiliar quem deseja olhar sua casa e finalmente repetir: \u201clar, doce lar\u201d.<\/p>\n<p>Gostou do artigo? <a href=\"https:\/\/guairaimoveis.com.br\/blog\/as-5-imobiliarias-mais-atentas-de-santo-andre\/\" target=\"_blank\" rel=\"noopener\">Veja o nosso \u00faltimo aqui!<\/a><\/p>\n<p><a href=\"http:\/\/www.guairaimoveis.com.br\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1546\" title=\"botao entre em contato imobiliaria guaira imoveis\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2018\/07\/48265-entre-em-contato-imobiliaria-guaira.png\" alt=\"\" width=\"201\" height=\"95\" \/><\/a> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1545 size-full\" title=\"botao posts do blog imobiliaria guaira imoveis\" src=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/03\/posts-do-blog-imobiliaria-guaira.png\" alt=\"\" width=\"300\" height=\"150\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decorar a piscina com plantas \u00e9 sempre uma excelente ideia para deixar o ambiente mais aconchegante e belo; veja essas dicas da Imobili\u00e1ria Gua\u00edra. A Imobili\u00e1ria Gua\u00edra v\u00ea a primavera se aproximando e j\u00e1 come\u00e7a a pensar em piscina. N\u00e3o podemos sentir aquele calorzinho chegando sem imaginar um bom banho para refrescar o forte calor [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[214,280,328],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plantas para decorar a piscina: confira as dicas da Imobili\u00e1ria Gua\u00edra - Blog da Gua\u00edra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plantas para decorar a piscina: confira as dicas da Imobili\u00e1ria Gua\u00edra - Blog da Gua\u00edra\" \/>\n<meta property=\"og:description\" content=\"Decorar a piscina com plantas \u00e9 sempre uma excelente ideia para deixar o ambiente mais aconchegante e belo; veja essas dicas da Imobili\u00e1ria Gua\u00edra. A Imobili\u00e1ria Gua\u00edra v\u00ea a primavera se aproximando e j\u00e1 come\u00e7a a pensar em piscina. N\u00e3o podemos sentir aquele calorzinho chegando sem imaginar um bom banho para refrescar o forte calor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Gua\u00edra\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-11T14:19:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T15:50:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jos\u00e9 Catojo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jos\u00e9 Catojo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plantas para decorar a piscina: confira as dicas da Imobili\u00e1ria Gua\u00edra - Blog da Gua\u00edra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/","og_locale":"pt_BR","og_type":"article","og_title":"Plantas para decorar a piscina: confira as dicas da Imobili\u00e1ria Gua\u00edra - Blog da Gua\u00edra","og_description":"Decorar a piscina com plantas \u00e9 sempre uma excelente ideia para deixar o ambiente mais aconchegante e belo; veja essas dicas da Imobili\u00e1ria Gua\u00edra. A Imobili\u00e1ria Gua\u00edra v\u00ea a primavera se aproximando e j\u00e1 come\u00e7a a pensar em piscina. N\u00e3o podemos sentir aquele calorzinho chegando sem imaginar um bom banho para refrescar o forte calor [&hellip;]","og_url":"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/","og_site_name":"Blog da Gua\u00edra","article_published_time":"2018-09-11T14:19:21+00:00","article_modified_time":"2024-01-31T15:50:30+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/09\/piscina-em-imovel-e-imobiliaria-guaira-5.png","type":"image\/png"}],"author":"Jos\u00e9 Catojo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jos\u00e9 Catojo","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/#article","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/"},"author":{"name":"Jos\u00e9 Catojo","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/bae3f2d70f3e6dee82d826e5dbea360a"},"headline":"Plantas para decorar a piscina: confira as dicas da Imobili\u00e1ria Gua\u00edra","datePublished":"2018-09-11T14:19:21+00:00","dateModified":"2024-01-31T15:50:30+00:00","mainEntityOfPage":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/"},"wordCount":848,"commentCount":0,"publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"keywords":["dicas da Imobili\u00e1ria Gua\u00edra","Gua\u00edra Im\u00f3veis","imobili\u00e1ria gua\u00edra"],"articleSection":["Dicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/","url":"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/","name":"Plantas para decorar a piscina: confira as dicas da Imobili\u00e1ria Gua\u00edra - Blog da Gua\u00edra","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#website"},"datePublished":"2018-09-11T14:19:21+00:00","dateModified":"2024-01-31T15:50:30+00:00","breadcrumb":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/guairaimoveis.com.br\/blog\/plantas-para-decorar-a-piscina-confira-as-dicas-da-imobiliaria-guaira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/guairaimoveis.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Plantas para decorar a piscina: confira as dicas da Imobili\u00e1ria Gua\u00edra"}]},{"@type":"WebSite","@id":"https:\/\/guairaimoveis.com.br\/blog\/#website","url":"https:\/\/guairaimoveis.com.br\/blog\/","name":"Blog da Gua\u00edra","description":"Aqui voc\u00ea vai encontrar conte\u00fados incr\u00edveis sobre o mercado imobili\u00e1rio e tirar todas as d\u00favidas que voc\u00ea tem na hora de comprar, alugar ou negociar um im\u00f3vel.","publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"alternateName":"Gua\u00edra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guairaimoveis.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization","name":"Blog da Gua\u00edra","url":"https:\/\/guairaimoveis.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","contentUrl":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","width":200,"height":55,"caption":"Blog da Gua\u00edra"},"image":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/bae3f2d70f3e6dee82d826e5dbea360a","name":"Jos\u00e9 Catojo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b3e874c98c22d229d4d4d617a50434df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b3e874c98c22d229d4d4d617a50434df?s=96&d=mm&r=g","caption":"Jos\u00e9 Catojo"},"url":"https:\/\/guairaimoveis.com.br\/blog\/author\/josecatojo\/"}]}},"_links":{"self":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/1883"}],"collection":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1883"}],"version-history":[{"count":2,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/1883\/revisions"}],"predecessor-version":[{"id":5606,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/1883\/revisions\/5606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media\/1889"}],"wp:attachment":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}