
{"id":2250,"date":"2019-02-14T11:22:36","date_gmt":"2019-02-14T13:22:36","guid":{"rendered":"https:\/\/atomic-temporary-126015677.wpcomstaging.com\/?p=2250"},"modified":"2024-01-31T13:00:04","modified_gmt":"2024-01-31T16:00:04","slug":"a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje","status":"publish","type":"post","link":"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/","title":{"rendered":"A Imobili\u00e1ria Gua\u00edra te d\u00e1 3 motivos para morar em Santo Andr\u00e9 HOJE"},"content":{"rendered":"<p><strong>Morar em Santo Andr\u00e9<\/strong> \u00e9 algo que realmente encanta. Bairrismos \u00e0 parte, a cidade tem motivo de sobras para atrair novos moradores. Com um encanto ao atrav\u00e9s a fronteira dentro da <a href=\"https:\/\/guairaimoveis.com.br\/blog\/imobiliarias-no-abc-que-investem-em-pessoas\/\" target=\"_blank\" rel=\"noopener\"><strong>Regi\u00e3o do ABC<\/strong><\/a>, Santo Andr\u00e9 definitivamente tem um charme especial.<\/p>\n<p>A <strong>Imobili\u00e1ria Gua\u00edra<\/strong> j\u00e1 est\u00e1 h\u00e1 anos no <a href=\"https:\/\/guairaimoveis.com.br\/blog\/aluguel-comercial-regras-normas-e-tudo-o-que-voce-precisa-saber\/\" target=\"_blank\" rel=\"noopener\"><strong>mercado imobili\u00e1rio<\/strong><\/a>. O encanto de quem chega \u00e0 cidade \u00e9 realmente diferenciado &#8211; e isso \u00e9 declarado em depoimentos pessoais de clientes que visitam a <strong>Gua\u00edra Neg\u00f3cios.<\/strong><\/p>\n<p>Um lugar realmente para chamar de lar. <strong>Morar em Santo Andr\u00e9<\/strong> \u00e9 bom pois \u00e9 calmo. <strong>Mudar para Santo Andr\u00e9<\/strong> \u00e9 necess\u00e1rio porque \u00e9 acolhedora. Permanecer em <strong>Santo Andr\u00e9<\/strong> \u00e9 fundamental.<\/p>\n<p>Uma cidade para construir uma vida, uma fam\u00edlia e uma identidade. Se voc\u00ea, por\u00e9m, ainda est\u00e1 na d\u00favida de onde dar um novo passo na sua vida, saiba que a Terra-M\u00e3e dos Paulistas est\u00e1 de bra\u00e7os abertos para voc\u00ea.<\/p>\n<p>A <strong>Gua\u00edra Im\u00f3veis<\/strong> separou tr\u00eas motivos pontuais que far\u00e3o voc\u00ea se mudar para Santo Andr\u00e9 hoje! Uma cidade totalmente diferente, sem igual no estado de S\u00e3o Paulo &#8211; ou ainda mais ousado &#8211; no Brasil.<\/p>\n<p>Uma cidade-lar. Que acolhe. Que d\u00e1 o suporte. E, sobretudo, que cuida.<\/p>\n<h2>3 motivos para morar em Santo Andr\u00e9<\/h2>\n<p><strong>Morar em Santo Andr\u00e9<\/strong> \u00e9 bom pois h\u00e1 parques, h\u00e1 acesso, h\u00e1 facilidade, h\u00e1 praticidade. Em todos os quesitos, desde sa\u00fade, transporte, educa\u00e7\u00e3o e seguran\u00e7a. <strong>Uma cidade completa<\/strong>, com pique de cidade de interior e tamanho de capital.<\/p>\n<h3>Morar em Santo Andr\u00e9 \u00e9 bom pois o tr\u00e2nsito n\u00e3o \u00e9 ca\u00f3tico<\/h3>\n<p>J\u00e1 imaginou uma cidade pr\u00f3xima \u00e0 capital, com todos os recursos, f\u00e1cil acesso a <strong>S\u00e3o Paulo<\/strong> e sem o ca\u00f3tico tr\u00e2nsito da megal\u00f3pole? Pois bem, <strong>Santo Andr\u00e9<\/strong> tem isso e muito mais, principalmente, pela organiza\u00e7\u00e3o do tr\u00e2nsito como um todo.<\/p>\n<p>Uma mobilidade urbana de primeiro mundo. \u00d4nibus que circulam, paradas modernas, ciclovias delimitadas e qualidade no transporte como um todo. Uma organiza\u00e7\u00e3o de tr\u00e2nsito que causa inveja em muita cidade maior.<\/p>\n<p>Morar em <strong>Santo Andr\u00e9<\/strong> \u00e9 morar em uma cidade que d\u00e1 acesso, permite transitar e garante a possibilidade de evoluir. Parado, ningu\u00e9m avan\u00e7a. Para avan\u00e7ar, \u00e9 necess\u00e1ria mobilidade eficiente e de qualidade.<\/p>\n<h3>Morar em Santo Andr\u00e9 \u00e9 bom pois \u00e9 uma cidade calma, mas com tudo acess\u00edvel<\/h3>\n<p>Santo Andr\u00e9 \u00e9 uma cidade com tamanho de metr\u00f3pole, mas pique de interior. Contando com mais de meio milh\u00e3o de habitantes, imagina-se que o caos seja presente, a inseguran\u00e7a seja constante e problemas sejam di\u00e1rios.<\/p>\n<p>Como toda a cidade, problemas existem, mas a calmaria da cidade impressiona. A cidade \u00e9 tida como uma das mais seguras de S\u00e3o Paulo. Permite, portanto, uma vida ao ar livre, caminhar com seguran\u00e7a, e, principalmente, para quem deseja um <strong>lugar calmo para criar a fam\u00edlia.<\/strong><\/p>\n<p>Uma cidade diferente que acolhe pela calmaria e faz permanecer pela acessibilidade. Um local seguro para quem deseja construir sem ser importunado, e para quem deseja crescer com suporte adequado.<\/p>\n<h3>Morar em Santo Andr\u00e9 \u00e9 bom pois h\u00e1 lazer e qualidade de vida<\/h3>\n<p>A vida em <strong>Santo Andr\u00e9<\/strong> \u00e9 tranquila, e ainda estimula muito mais por promover qualidade de vida e proporcionar lazer. Esses dois elementos s\u00e3o raros nas cidades atualmente. Encarceradas pela inseguran\u00e7a, as pessoas t\u00eam permanecido muito mais dentro de casa.<\/p>\n<p>Mudar para <strong>Santo Andr\u00e9<\/strong> hoje \u00e9 mudar para melhor. Sair nas ruas, participar de eventos, estar em pra\u00e7as, tomar um sorvete, aproveitar o sol\u2026 enfim, aquilo que a vida tem a proporcionar.<\/p>\n<p>Quando decidir mudar para Santo Andr\u00e9, saiba que uma vida de empolga\u00e7\u00e3o, qualidade e lazer n\u00e3o faltar\u00e3o. \u00c9 aproveitar o melhor do que realmente vale: o presente.<\/p>\n<h2>Para morar em Santo Andr\u00e9, basta contatar a Imobili\u00e1ria Gua\u00edra<\/h2>\n<p>Op\u00e7\u00f5es para todos os gostos, <strong>im\u00f3veis de todas as prefer\u00eancias<\/strong>. O local ideal, a <strong>Imobili\u00e1ria Gua\u00edra<\/strong> encontra. Morar em Santo Andr\u00e9 \u00e9 bom <a href=\"https:\/\/guairaimoveis.com.br\/blog\/5-ideias-de-plantas-para-apartamento-para-cultivar-em-casa\/\" target=\"_blank\" rel=\"noopener\">pois todo lugar \u00e9 lar<\/a>, e todo lugar \u00e9 particular.<\/p>\n<p>Por isso, morar numa cidade que te realize \u00e9 fundamental. Energias s\u00e3o trocadas, boas sensa\u00e7\u00f5es explanadas, e a certeza do bem-estar \u00e9 muito maior.<\/p>\n<p>A <strong>Imobili\u00e1ria Gua\u00edra<\/strong> preza muito por isso. Ao sugerir um im\u00f3vel, a sugest\u00e3o \u00e9 de um novo lar. Um lugar para chamar de casa, em um local novo, que, pelo lado positivo, aconchega como poucos.<\/p>\n<p>Gostou do artigo? Deixe seu coment\u00e1rio, \u00e9 importante para n\u00f3s!<br \/>\nAH! S\u00f3 lembrando, j\u00e1\u00a0conhece a\u00a0<strong>credpago? Aluguel f\u00e1cil?<\/strong> Se n\u00e3o, clique na imagem abaixo!<\/p>\n<p><a href=\"http:\/\/soumais.guairaimoveis.com.br\/aluguel-sem-fiador\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2138 size-full\" title=\"bot\u00e3o credpago aluguel f\u00e1cil com imobili\u00e1ria gua\u00edra im\u00f3veis\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2019\/01\/credipago.jpg\" alt=\"\" width=\"970\" height=\"300\" srcset=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2019\/01\/credipago.jpg 970w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2019\/01\/credipago-300x93.jpg 300w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2019\/01\/credipago-768x238.jpg 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.guairaimoveis.com.br\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1546\" title=\"bot\u00e3o contato com imobili\u00e1ria gua\u00edra em santo andr\u00e9 e im\u00f3veis\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2018\/07\/48265-entre-em-contato-imobiliaria-guaira.png\" alt=\"\" width=\"140\" height=\"87\" \/><\/a> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1545 size-full\" title=\"bot\u00e3o blog da imobili\u00e1ria de santo andr\u00e9 gua\u00edra im\u00f3veis\" src=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2018\/03\/posts-do-blog-imobiliaria-guaira.png\" alt=\"\" width=\"300\" height=\"150\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morar em Santo Andr\u00e9 \u00e9 algo que realmente encanta. Bairrismos \u00e0 parte, a cidade tem motivo de sobras para atrair novos moradores. Com um encanto ao atrav\u00e9s a fronteira dentro da Regi\u00e3o do ABC, Santo Andr\u00e9 definitivamente tem um charme especial. A Imobili\u00e1ria Gua\u00edra j\u00e1 est\u00e1 h\u00e1 anos no mercado imobili\u00e1rio. O encanto de quem [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,8],"tags":[78,280,316,321,325,326,328,381,455],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Imobili\u00e1ria Gua\u00edra te d\u00e1 3 motivos para morar em Santo Andr\u00e9 HOJE<\/title>\n<meta name=\"description\" content=\"Voc\u00ea j\u00e1 estava pensando em se mudar? Que tal morar em Santo Andr\u00e9? A Gua\u00edra Im\u00f3veis te d\u00e1 3 motivos para uma mudan\u00e7a imediatamente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Imobili\u00e1ria Gua\u00edra te d\u00e1 3 motivos para morar em Santo Andr\u00e9 HOJE\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea j\u00e1 estava pensando em se mudar? Que tal morar em Santo Andr\u00e9? A Gua\u00edra Im\u00f3veis te d\u00e1 3 motivos para uma mudan\u00e7a imediatamente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Gua\u00edra\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-14T13:22:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T16:00:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/03\/20bb2-santo-andre-otimo-para-morar-e-imobiliaria-guaira-imoveis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jos\u00e9 Catojo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jos\u00e9 Catojo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Imobili\u00e1ria Gua\u00edra te d\u00e1 3 motivos para morar em Santo Andr\u00e9 HOJE","description":"Voc\u00ea j\u00e1 estava pensando em se mudar? Que tal morar em Santo Andr\u00e9? A Gua\u00edra Im\u00f3veis te d\u00e1 3 motivos para uma mudan\u00e7a imediatamente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/","og_locale":"pt_BR","og_type":"article","og_title":"A Imobili\u00e1ria Gua\u00edra te d\u00e1 3 motivos para morar em Santo Andr\u00e9 HOJE","og_description":"Voc\u00ea j\u00e1 estava pensando em se mudar? Que tal morar em Santo Andr\u00e9? A Gua\u00edra Im\u00f3veis te d\u00e1 3 motivos para uma mudan\u00e7a imediatamente.","og_url":"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/","og_site_name":"Blog da Gua\u00edra","article_published_time":"2019-02-14T13:22:36+00:00","article_modified_time":"2024-01-31T16:00:04+00:00","og_image":[{"width":900,"height":400,"url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/03\/20bb2-santo-andre-otimo-para-morar-e-imobiliaria-guaira-imoveis.jpg","type":"image\/jpeg"}],"author":"Jos\u00e9 Catojo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jos\u00e9 Catojo","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/#article","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/"},"author":{"name":"Jos\u00e9 Catojo","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/bae3f2d70f3e6dee82d826e5dbea360a"},"headline":"A Imobili\u00e1ria Gua\u00edra te d\u00e1 3 motivos para morar em Santo Andr\u00e9 HOJE","datePublished":"2019-02-14T13:22:36+00:00","dateModified":"2024-01-31T16:00:04+00:00","mainEntityOfPage":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/"},"wordCount":770,"commentCount":0,"publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"keywords":["Bairros Santo Andr\u00e9","Gua\u00edra Im\u00f3veis","imobiliaria","Imobili\u00e1ria abc","Imobili\u00e1ria em Santo Andr\u00e9","Imobili\u00e1ria em S\u00e3o Bernardo do Campo","imobili\u00e1ria gua\u00edra","Morar em Santo Andr\u00e9","santo andr\u00e9"],"articleSection":["Mercado Imobili\u00e1rio","Neg\u00f3cios e Vendas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/","url":"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/","name":"A Imobili\u00e1ria Gua\u00edra te d\u00e1 3 motivos para morar em Santo Andr\u00e9 HOJE","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#website"},"datePublished":"2019-02-14T13:22:36+00:00","dateModified":"2024-01-31T16:00:04+00:00","description":"Voc\u00ea j\u00e1 estava pensando em se mudar? Que tal morar em Santo Andr\u00e9? A Gua\u00edra Im\u00f3veis te d\u00e1 3 motivos para uma mudan\u00e7a imediatamente.","breadcrumb":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/guairaimoveis.com.br\/blog\/a-imobiliaria-guaira-te-da-3-motivos-para-morar-em-santo-andre-hoje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/guairaimoveis.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"A Imobili\u00e1ria Gua\u00edra te d\u00e1 3 motivos para morar em Santo Andr\u00e9 HOJE"}]},{"@type":"WebSite","@id":"https:\/\/guairaimoveis.com.br\/blog\/#website","url":"https:\/\/guairaimoveis.com.br\/blog\/","name":"Blog da Gua\u00edra","description":"Aqui voc\u00ea vai encontrar conte\u00fados incr\u00edveis sobre o mercado imobili\u00e1rio e tirar todas as d\u00favidas que voc\u00ea tem na hora de comprar, alugar ou negociar um im\u00f3vel.","publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"alternateName":"Gua\u00edra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guairaimoveis.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization","name":"Blog da Gua\u00edra","url":"https:\/\/guairaimoveis.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","contentUrl":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","width":200,"height":55,"caption":"Blog da Gua\u00edra"},"image":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/bae3f2d70f3e6dee82d826e5dbea360a","name":"Jos\u00e9 Catojo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b3e874c98c22d229d4d4d617a50434df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b3e874c98c22d229d4d4d617a50434df?s=96&d=mm&r=g","caption":"Jos\u00e9 Catojo"},"url":"https:\/\/guairaimoveis.com.br\/blog\/author\/josecatojo\/"}]}},"_links":{"self":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/2250"}],"collection":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2250"}],"version-history":[{"count":2,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/2250\/revisions"}],"predecessor-version":[{"id":5666,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/2250\/revisions\/5666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media\/2253"}],"wp:attachment":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}