
{"id":4768,"date":"2022-10-05T10:40:07","date_gmt":"2022-10-05T13:40:07","guid":{"rendered":"https:\/\/blogdaguaira.com.br\/?p=4768"},"modified":"2022-10-27T11:01:43","modified_gmt":"2022-10-27T14:01:43","slug":"outubro-rosa-na-guaira","status":"publish","type":"post","link":"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/","title":{"rendered":"Outubro Rosa na Gua\u00edra"},"content":{"rendered":"\n<p>Todos os anos, o m\u00eas \u00e9 marcado pelo Outubro Rosa, que \u00e9 marcado por uma s\u00e9rie de a\u00e7\u00f5es em prol da conscientiza\u00e7\u00e3o \u00e0 preven\u00e7\u00e3o do c\u00e2ncer de mama. Apesar de todos os avan\u00e7os da medicina, o de mama ainda \u00e9 a maior causa de c\u00e2ncer em mulheres e a maior arma contra a doen\u00e7a ainda \u00e9 o diagn\u00f3stico precoce. A Gua\u00edra adere ao Outubro Rosa com a\u00e7\u00f5es internas e externas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Origem do Outubro Rosa<\/h2>\n\n\n\n<p>V\u00e1rias iniciativas pelo diagn\u00f3stico precoce do c\u00e2ncer de mama come\u00e7aram a ser realizadas a partir da d\u00e9cada de 1980. A\u00e7\u00f5es isoladas como corridas, distribui\u00e7\u00f5es de panfletos e campanhas de conscientiza\u00e7\u00e3o come\u00e7aram a ser realizadas nos Estados Unidos na d\u00e9cada de 80 durante todo o ano. A primeira faixa para simbolizar a luta foi cor de p\u00eassego, e n\u00e3o o rosa.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2022\/10\/64c242f0-27c1-4924-bd7d-7c08292bbd29-1024x768.jpg\" alt=\"\" class=\"wp-image-4770\" width=\"768\" height=\"576\" srcset=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/64c242f0-27c1-4924-bd7d-7c08292bbd29-1024x768.jpg 1024w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/64c242f0-27c1-4924-bd7d-7c08292bbd29-300x225.jpg 300w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/64c242f0-27c1-4924-bd7d-7c08292bbd29-768x576.jpg 768w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/64c242f0-27c1-4924-bd7d-7c08292bbd29.jpg 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n<p class=\"has-pale-pink-background-color has-background\">No outono de 1991 a Funda\u00e7\u00e3o Susan G. Komen distribuiu fitas rosas aos participantes de uma corrida promovida em Nova York para sobreviventes de c\u00e2ncer de mama. Aos poucos, todas as a\u00e7\u00f5es foram convergindo para o m\u00eas de outubro e com a cor rosa como s\u00edmbolo. Por exemplo, quando em 1993 a Est\u00e9e Lauder, uma empresa de cosm\u00e9ticos, fundou a Breast Cancer Research Foundation e adotou a faixa rosa como logotipo.  A partir destas a\u00e7\u00f5es, o movimento s\u00f3 cresceu e hoje \u00e9 disseminado por todo o mundo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Outubro Rosa na Gua\u00edra<\/h2>\n\n\n\n<p>A Gua\u00edra participa ativamente do Outubro Rosa. Durante todo o m\u00eas promove a\u00e7\u00f5es internas e externas de conscientiza\u00e7\u00e3o de colaboradoras e clientes, al\u00e9m de adotar a cor rosa em todas as suas a\u00e7\u00f5es de marketing e redes sociais. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2022\/10\/6.jpg\" alt=\"\" class=\"wp-image-4780\" width=\"766\" height=\"556\" srcset=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/6.jpg 1021w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/6-300x218.jpg 300w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/6-768x557.jpg 768w\" sizes=\"(max-width: 766px) 100vw, 766px\" \/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">O c\u00e2ncer de mama<\/h2>\n\n\n\n<p>Apesar de todas as a\u00e7\u00f5es tomadas em n\u00edvel mundial pela conscientiza\u00e7\u00e3o do diagn\u00f3stico precoce, o c\u00e2ncer de mama segue sendo a mais recorrente causa da doen\u00e7a entre as mulheres. No Brasil, <a href=\"https:\/\/www.gov.br\/inca\/pt-br\/assuntos\/cancer\/numeros\" target=\"_blank\" rel=\"noreferrer noopener\">29% dos casos de c\u00e2ncer em mulheres \u00e9 de mama, e infelizmente, dentro destes casos, cerca de 16% acabam sendo fatais<\/a>. Lamentavelmente, muitas destas mortes poderiam ser evitadas se a doen\u00e7a tivesse sido descoberta com maior anteced\u00eancia. Como em qualquer c\u00e2ncer, quanto mais cedo o diagn\u00f3stico maior as chances de cura com tratamentos adequados. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Casos de c\u00e2ncer de mama em homens<\/h2>\n\n\n\n<p>Os homens tamb\u00e9m possuem gl\u00e2ndulas mam\u00e1rias, e por isso, mesmo que em taxas muito inferiores, podem desenvolver casos de c\u00e2ncer de mama. Cerca de 1% dos casos masculinos s\u00e3o na mama, e por isso qualquer sinal de incha\u00e7o, dor ou desconforto nas mamas ou mamilos devem ser observados e comunicados a um m\u00e9dico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como fazer o auto-exame?<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdaguaira.com.br\/wp-content\/uploads\/2022\/10\/1f282ef1-6717-48b7-b726-61539797a941-1024x682.jpg\" alt=\"\" class=\"wp-image-4771\" width=\"256\" height=\"171\" srcset=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/1f282ef1-6717-48b7-b726-61539797a941-1024x682.jpg 1024w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/1f282ef1-6717-48b7-b726-61539797a941-300x200.jpg 300w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/1f282ef1-6717-48b7-b726-61539797a941-768x512.jpg 768w, https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/1f282ef1-6717-48b7-b726-61539797a941.jpg 1280w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/figure><\/div>\n\n\n<p class=\"has-pale-pink-background-color has-background\">A t\u00e9cnica mais utilizada de auto-exame \u00e9 colocar um dos bra\u00e7os atr\u00e1s da cabe\u00e7a e apalpar com a m\u00e3o a mama do lado levantado, buscando qualquer n\u00f3dulo, e repetir a mesma a\u00e7\u00e3o do outro lado. Por\u00e9m, as mulheres devem ficar atentas a qualquer sinal de altera\u00e7\u00e3o em suas mamas. Incha\u00e7os, desconfortos, manchas ou dores devem ser comunicadas rapidamente a um m\u00e9dico. Por\u00e9m, regularmente podem fazer uma busca ativa de qualquer sinal. <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos os anos, o m\u00eas \u00e9 marcado pelo Outubro Rosa, que \u00e9 marcado por uma s\u00e9rie de a\u00e7\u00f5es em prol da conscientiza\u00e7\u00e3o \u00e0 preven\u00e7\u00e3o do c\u00e2ncer de mama. Apesar de todos os avan\u00e7os da medicina, o de mama ainda \u00e9 a maior causa de c\u00e2ncer em mulheres e a maior arma contra a doen\u00e7a ainda [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[326,328],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Outubro Rosa na Gua\u00edra - Blog da Gua\u00edra<\/title>\n<meta name=\"description\" content=\"A Gua\u00edra Im\u00f3veis adota diversas a\u00e7\u00f5es no Outubro Rosa visando o esclarecimento de colaboradoras e clientes sobre o c\u00e2ncer de mama\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Outubro Rosa na Gua\u00edra - Blog da Gua\u00edra\" \/>\n<meta property=\"og:description\" content=\"A Gua\u00edra Im\u00f3veis adota diversas a\u00e7\u00f5es no Outubro Rosa visando o esclarecimento de colaboradoras e clientes sobre o c\u00e2ncer de mama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Gua\u00edra\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-05T13:40:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-27T14:01:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"673\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guaira Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guaira Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Outubro Rosa na Gua\u00edra - Blog da Gua\u00edra","description":"A Gua\u00edra Im\u00f3veis adota diversas a\u00e7\u00f5es no Outubro Rosa visando o esclarecimento de colaboradoras e clientes sobre o c\u00e2ncer de mama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/","og_locale":"pt_BR","og_type":"article","og_title":"Outubro Rosa na Gua\u00edra - Blog da Gua\u00edra","og_description":"A Gua\u00edra Im\u00f3veis adota diversas a\u00e7\u00f5es no Outubro Rosa visando o esclarecimento de colaboradoras e clientes sobre o c\u00e2ncer de mama","og_url":"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/","og_site_name":"Blog da Gua\u00edra","article_published_time":"2022-10-05T13:40:07+00:00","article_modified_time":"2022-10-27T14:01:43+00:00","og_image":[{"width":673,"height":290,"url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/10\/1.jpg","type":"image\/jpeg"}],"author":"Guaira Marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Guaira Marketing","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/#article","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/"},"author":{"name":"Guaira Marketing","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/39db4ee78e69c43c682166fc93ff3a19"},"headline":"Outubro Rosa na Gua\u00edra","datePublished":"2022-10-05T13:40:07+00:00","dateModified":"2022-10-27T14:01:43+00:00","mainEntityOfPage":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/"},"wordCount":548,"commentCount":0,"publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"keywords":["Imobili\u00e1ria em S\u00e3o Bernardo do Campo","imobili\u00e1ria gua\u00edra"],"articleSection":["imobili\u00e1ria gua\u00edra"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/","url":"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/","name":"Outubro Rosa na Gua\u00edra - Blog da Gua\u00edra","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#website"},"datePublished":"2022-10-05T13:40:07+00:00","dateModified":"2022-10-27T14:01:43+00:00","description":"A Gua\u00edra Im\u00f3veis adota diversas a\u00e7\u00f5es no Outubro Rosa visando o esclarecimento de colaboradoras e clientes sobre o c\u00e2ncer de mama","breadcrumb":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/guairaimoveis.com.br\/blog\/outubro-rosa-na-guaira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/guairaimoveis.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Outubro Rosa na Gua\u00edra"}]},{"@type":"WebSite","@id":"https:\/\/guairaimoveis.com.br\/blog\/#website","url":"https:\/\/guairaimoveis.com.br\/blog\/","name":"Blog da Gua\u00edra","description":"Aqui voc\u00ea vai encontrar conte\u00fados incr\u00edveis sobre o mercado imobili\u00e1rio e tirar todas as d\u00favidas que voc\u00ea tem na hora de comprar, alugar ou negociar um im\u00f3vel.","publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"alternateName":"Gua\u00edra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guairaimoveis.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization","name":"Blog da Gua\u00edra","url":"https:\/\/guairaimoveis.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","contentUrl":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","width":200,"height":55,"caption":"Blog da Gua\u00edra"},"image":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/39db4ee78e69c43c682166fc93ff3a19","name":"Guaira Marketing","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b183f2af4104df93cd4de7e7a96f7f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b183f2af4104df93cd4de7e7a96f7f1?s=96&d=mm&r=g","caption":"Guaira Marketing"},"sameAs":["guairamkt"],"url":"https:\/\/guairaimoveis.com.br\/blog\/author\/guairamkt\/"}]}},"_links":{"self":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/4768"}],"collection":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4768"}],"version-history":[{"count":10,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/4768\/revisions"}],"predecessor-version":[{"id":4812,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/4768\/revisions\/4812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media\/4779"}],"wp:attachment":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}