
{"id":5847,"date":"2024-08-28T11:23:42","date_gmt":"2024-08-28T14:23:42","guid":{"rendered":"https:\/\/guairaimoveis.com.br\/blog\/?p=5847"},"modified":"2024-09-02T11:24:23","modified_gmt":"2024-09-02T14:24:23","slug":"fundo-de-reserva","status":"publish","type":"post","link":"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/","title":{"rendered":"Quem paga o fundo de reserva do condom\u00ednio: inquilino ou propriet\u00e1rio?"},"content":{"rendered":"\n<p>Reserva financeira de emerg\u00eancia. Voc\u00ea tem?<\/p>\n\n\n\n<p>Bom, de acordo com o DataFolha, cerca de 67% dos brasileiros n\u00e3o tem uma reserva financeira de emerg\u00eancia. Tudo bem, apesar deste recurso ser importante em caso de imprevistos, n\u00e3o existe uma lei que obrigue as pessoas a guardarem dinheiro.<\/p>\n\n\n\n<p>O problema \u00e9 que, no caso de condom\u00ednios residenciais, \u00e9 sim obrigat\u00f3rio ter dinheiro em caixa, o tal <strong>fundo de reserva<\/strong>. De acordo com a <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/L4591.htm\" target=\"_blank\" rel=\"noreferrer noopener\">Lei do Condom\u00ednio (Lei n\u00ba 4.591\/64)<\/a>, a conven\u00e7\u00e3o condominial \u00e9 respons\u00e1vel por instituir os seguintes aspectos do fundo de reserva:<\/p>\n\n\n\n<ul>\n<li>C\u00e1lculo do rateio do valor<\/li>\n\n\n\n<li>Cobertura de despesas ordin\u00e1rias ou extraordin\u00e1rias<\/li>\n\n\n\n<li>Prazo da cobran\u00e7a em per\u00edodo determinado ou indeterminado<\/li>\n\n\n\n<li>Valor da contribui\u00e7\u00e3o, conforme a porcentagem da cota condominial (de 5% a 10%)<\/li>\n<\/ul>\n\n\n\n<p>Estipular esses indicadores \u00e9 essencial para sempre ter dinheiro no fundo de reserva para cobrir urg\u00eancias.&nbsp;<\/p>\n\n\n\n<p>Mas, o que voc\u00ea, futuro morador de condom\u00ednio, tem a ver com isso? Bem, continue a leitura e saiba quais as responsabilidades de moradores de condom\u00ednio em rela\u00e7\u00e3o ao fundo de reserva.<\/p>\n\n\n\n<p>Come\u00e7ando pelo b\u00e1sico\u2026<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O QUE \u00c9 O FUNDO DE RESERVA?<\/strong><\/h2>\n\n\n\n<p>\u00c9 uma poupan\u00e7a que o condom\u00ednio tem dispon\u00edvel em caixa para cobrir gastos emergenciais e investimentos n\u00e3o previstos, como uma reforma ou substitui\u00e7\u00e3o de equipamentos. O fundo de reserva tamb\u00e9m pode ser usado para pagar inadimpl\u00eancias de moradores ou uma obra a longo prazo.<\/p>\n\n\n\n<p>Por ser um estoque de dinheiro reservado para emerg\u00eancias, est\u00e1 depositado em uma conta separada da opera\u00e7\u00e3o rotineira do condom\u00ednio.<\/p>\n\n\n\n<p>A principal inten\u00e7\u00e3o do fundo de reserva \u00e9 preservar a seguran\u00e7a financeira do empreendimento, evitando que o dinheiro do dia a dia seja usado para imprevistos e, consequentemente, faltem recursos para as contas b\u00e1sicas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>QUEM PAGA O FUNDO DE RESERVA?<\/strong><\/h2>\n\n\n\n<p>Essa \u00e9 a pergunta que n\u00e3o quer calar e deixa muita gente preocupada. Afinal, se voc\u00ea n\u00e3o tem um reserva de emerg\u00eancia nem pra voc\u00ea&#8230; que dir\u00e1 para o condom\u00ednio.<\/p>\n\n\n\n<p>Muita calma nessa hora. Se voc\u00ea \u00e9 inquilino, boas not\u00edcias: esse boleto n\u00e3o te pertence!&nbsp;<\/p>\n\n\n\n<p>O pagamento do fundo de reserva \u00e9 uma obrigatoriedade mensal do propriet\u00e1rio do im\u00f3vel. Segundo a Lei do Inquilinato, o propriet\u00e1rio \u00e9 respons\u00e1vel pelo pagamento das contas extraordin\u00e1rias:<\/p>\n\n\n\n<ul>\n<li>Fundo de reserva<\/li>\n\n\n\n<li>Sal\u00e1rios e encargos trabalhistas<\/li>\n\n\n\n<li>Manuten\u00e7\u00e3o e conserva\u00e7\u00e3o das \u00e1reas comuns<\/li>\n\n\n\n<li>Limpeza, conserva\u00e7\u00e3o e pintura das \u00e1reas comuns<\/li>\n\n\n\n<li>Contas de \u00e1gua, esgoto, g\u00e1s, luz e energia das \u00e1reas comuns<\/li>\n<\/ul>\n\n\n\n<p>No entanto&#8230; caso uma parte do fundo de reserva seja usado para uma obra emergencial, o dinheiro precisa ser reposto e o inquilino arca com essa conta.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>QUAL O VALOR DO FUNDO DE RESERVA?<\/strong><\/h2>\n\n\n\n<p>N\u00e3o existe uma quantia padr\u00e3o a ser arrecadada e a legisla\u00e7\u00e3o prev\u00ea que a conven\u00e7\u00e3o do condom\u00ednio estipule o valor da contribui\u00e7\u00e3o, seguindo um dos seguintes c\u00e1lculos:<\/p>\n\n\n\n<p><strong>Porcentagem fixa<\/strong><\/p>\n\n\n\n<p>Cobran\u00e7a de 5% a 10% da cota condominial ordin\u00e1ria. Ou seja, se a taxa condominial custa R$ 500, a contribui\u00e7\u00e3o para o fundo de reserva fica entre R$ 25 a R$ 50.<\/p>\n\n\n\n<p><strong>Valor espec\u00edfico<\/strong><\/p>\n\n\n\n<p>A contribui\u00e7\u00e3o mensal para o fundo de reserva recebe um valor estipulado, independentemente do valor da taxa condominial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>DICAS PARA INQUILINOS E PROPRIET\u00c1RIOS<\/strong><\/h2>\n\n\n\n<p>Seja voc\u00ea inquilino ou propriet\u00e1rio, \u00e9 importante entender alguns pontos espec\u00edficos relacionados ao fundo de reserva, para n\u00e3o ser surpreendido com o caixa do condom\u00ednio zerado e despesas inesperadas chegando na sua conta.<\/p>\n\n\n\n<p><strong>Leia o contrato de loca\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>J\u00e1 falamos por aqui que o respons\u00e1vel pelo pagamento do fundo de reserva \u00e9 o propriet\u00e1rio, por\u00e9m, alguns contratos de loca\u00e7\u00e3o podem prever que o inquilino fa\u00e7a o reembolso deste valor, referente ao per\u00edodo da loca\u00e7\u00e3o.<\/p>\n\n\n\n<p>Se houver essa cl\u00e1usula no contrato, vale uma negocia\u00e7\u00e3o entre inquilino e propriet\u00e1rio para modificar essa condi\u00e7\u00e3o ou obter um desconto no aluguel.<\/p>\n\n\n\n<p><strong>Guarde os comprovantes<\/strong><\/p>\n\n\n\n<p>Se o inquilino for respons\u00e1vel por algum pagamento relacionado ao fundo de reserva, \u00e9 essencial guardar todos os comprovantes de pagamento. Isso pode evitar problemas futuros, principalmente na hora da devolu\u00e7\u00e3o do im\u00f3vel.<\/p>\n\n\n\n<p><strong>Qual a situa\u00e7\u00e3o do fundo de reserva?<\/strong><\/p>\n\n\n\n<p>Ao alugar um im\u00f3vel em condom\u00ednio, vale a pena perguntar sobre a situa\u00e7\u00e3o do fundo de reserva, para evitar surpresas com custos adicionais.&nbsp;<\/p>\n\n\n\n<p>Se o fundo de reserva \u00e9 uma obrigatoriedade do propriet\u00e1rio, ent\u00e3o&#8230; quais s\u00e3o as responsabilidades do inquilino? E os deveres?<\/p>\n\n\n\n<p><strong>SAIBA MAIS -><\/strong> <a href=\"https:\/\/guairaimoveis.com.br\/blog\/direitos-deveres-inquilino-do-apartamento\/\" target=\"_blank\" rel=\"noreferrer noopener\">Inquilino do apartamento: d\u00favidas, direitos e deveres<\/a>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O fundo de reserva do condom\u00ednio \u00e9 pago pelo inquilino ou propriet\u00e1rio? Se voc\u00ea n\u00e3o sabe do que se trata, clique e leia aqui.<\/p>\n","protected":false},"author":6,"featured_media":5848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quem paga o fundo de reserva: inquilino ou propriet\u00e1rio?<\/title>\n<meta name=\"description\" content=\"O fundo de reserva do condom\u00ednio \u00e9 pago pelo inquilino ou propriet\u00e1rio? Se voc\u00ea n\u00e3o sabe do que se trata, clique e leia aqui.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quem paga o fundo de reserva: inquilino ou propriet\u00e1rio?\" \/>\n<meta property=\"og:description\" content=\"O fundo de reserva do condom\u00ednio \u00e9 pago pelo inquilino ou propriet\u00e1rio? Se voc\u00ea n\u00e3o sabe do que se trata, clique e leia aqui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Gua\u00edra\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-28T14:23:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-02T14:24:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2024\/09\/26748.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guaira Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guaira Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quem paga o fundo de reserva: inquilino ou propriet\u00e1rio?","description":"O fundo de reserva do condom\u00ednio \u00e9 pago pelo inquilino ou propriet\u00e1rio? Se voc\u00ea n\u00e3o sabe do que se trata, clique e leia aqui.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/","og_locale":"pt_BR","og_type":"article","og_title":"Quem paga o fundo de reserva: inquilino ou propriet\u00e1rio?","og_description":"O fundo de reserva do condom\u00ednio \u00e9 pago pelo inquilino ou propriet\u00e1rio? Se voc\u00ea n\u00e3o sabe do que se trata, clique e leia aqui.","og_url":"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/","og_site_name":"Blog da Gua\u00edra","article_published_time":"2024-08-28T14:23:42+00:00","article_modified_time":"2024-09-02T14:24:23+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2024\/09\/26748.jpg","type":"image\/jpeg"}],"author":"Guaira Marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Guaira Marketing","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/#article","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/"},"author":{"name":"Guaira Marketing","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/39db4ee78e69c43c682166fc93ff3a19"},"headline":"Quem paga o fundo de reserva do condom\u00ednio: inquilino ou propriet\u00e1rio?","datePublished":"2024-08-28T14:23:42+00:00","dateModified":"2024-09-02T14:24:23+00:00","mainEntityOfPage":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/"},"wordCount":785,"commentCount":0,"publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"articleSection":["Condom\u00ednios"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/","url":"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/","name":"Quem paga o fundo de reserva: inquilino ou propriet\u00e1rio?","isPartOf":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#website"},"datePublished":"2024-08-28T14:23:42+00:00","dateModified":"2024-09-02T14:24:23+00:00","description":"O fundo de reserva do condom\u00ednio \u00e9 pago pelo inquilino ou propriet\u00e1rio? Se voc\u00ea n\u00e3o sabe do que se trata, clique e leia aqui.","breadcrumb":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/guairaimoveis.com.br\/blog\/fundo-de-reserva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/guairaimoveis.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Quem paga o fundo de reserva do condom\u00ednio: inquilino ou propriet\u00e1rio?"}]},{"@type":"WebSite","@id":"https:\/\/guairaimoveis.com.br\/blog\/#website","url":"https:\/\/guairaimoveis.com.br\/blog\/","name":"Blog da Gua\u00edra","description":"Aqui voc\u00ea vai encontrar conte\u00fados incr\u00edveis sobre o mercado imobili\u00e1rio e tirar todas as d\u00favidas que voc\u00ea tem na hora de comprar, alugar ou negociar um im\u00f3vel.","publisher":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization"},"alternateName":"Gua\u00edra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guairaimoveis.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/guairaimoveis.com.br\/blog\/#organization","name":"Blog da Gua\u00edra","url":"https:\/\/guairaimoveis.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","contentUrl":"https:\/\/guairaimoveis.com.br\/blog\/wp-content\/uploads\/2022\/04\/logo-200x55-1.png","width":200,"height":55,"caption":"Blog da Gua\u00edra"},"image":{"@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/39db4ee78e69c43c682166fc93ff3a19","name":"Guaira Marketing","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/guairaimoveis.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b183f2af4104df93cd4de7e7a96f7f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b183f2af4104df93cd4de7e7a96f7f1?s=96&d=mm&r=g","caption":"Guaira Marketing"},"sameAs":["guairamkt"],"url":"https:\/\/guairaimoveis.com.br\/blog\/author\/guairamkt\/"}]}},"_links":{"self":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/5847"}],"collection":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5847"}],"version-history":[{"count":2,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/5847\/revisions"}],"predecessor-version":[{"id":5850,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/posts\/5847\/revisions\/5850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media\/5848"}],"wp:attachment":[{"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guairaimoveis.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}